{"id":237,"count":8,"description":"","link":"https:\/\/www.archivesdumaroc.ma\/fr\/event_type\/archives-collectees\/","name":"Archives collect\u00e9es","slug":"archives-collectees","taxonomy":"event_type","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.archivesdumaroc.ma\/fr\/wp-json\/wp\/v2\/event_type\/237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivesdumaroc.ma\/fr\/wp-json\/wp\/v2\/event_type"}],"about":[{"href":"https:\/\/www.archivesdumaroc.ma\/fr\/wp-json\/wp\/v2\/taxonomies\/event_type"}]}}